{"id":649529,"date":"2026-06-16T11:10:49","date_gmt":"2026-06-16T09:10:49","guid":{"rendered":"https:\/\/mediafocus.ch\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/"},"modified":"2026-06-16T11:10:49","modified_gmt":"2026-06-16T09:10:49","slug":"le-marche-publicitaire-se-montre-stable-en-mai","status":"publish","type":"wbk_post_entry","link":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/","title":{"rendered":"Le march\u00e9 publicitaire se montre stable en mai"},"content":{"rendered":"<div class=\"wp-block-group wbk-group-post-overhead-title-container-block is-nowrap is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-post-date\"><time datetime=\"2026-06-16T11:10:49+02:00\" itemprop=\"datePublished\">16.06.2026<\/time><\/div><div class=\"wbk-category-list-block\"><\/div><\/div><h1 class=\"is-style-wbk-left-indentation-with-line wp-block-post-title\">Le march\u00e9 publicitaire se montre stable en mai<\/h1><div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile wbk-media-text-partner-promotion-block has-white-color has-text-color has-background has-link-color wp-elements-e0163866a58ae8f6bbee0124d7754c98\" style=\"background-color:#3e3e3e;grid-template-columns:auto 34%\">\n<div class=\"wp-block-media-text__content\">\n<h1 class=\"wp-block-heading has-white-color has-text-color has-link-color has-x-large-font-size wp-elements-9daad071f958645ee499bc12f72a1eb3\">Tendance du march\u00e9 publicitaire&nbsp;<\/h1>\n<p class=\"has-turquoise-color has-text-color has-link-color has-large-font-size wp-elements-915a0014f8b10a3af22d8e34f4e6d858 wp-block-paragraph\">Mai 2026<\/p>\n<\/div>\n<figure class=\"wp-block-media-text__media\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2025\/02\/Titelbild-Pfeil-neu-1024x576.png\" alt=\"\" class=\"wp-image-192968 size-full\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Apr\u00e8s un mois d\u2019avril stable, le mois de mai est \u00e9galement rest\u00e9 positif. Il a g\u00e9n\u00e9r\u00e9 <strong>354.6&nbsp;millions de CHF<\/strong>, soit un peu plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente (<strong>+0.2%<\/strong>). En mai, le march\u00e9 classique a atteint une <strong>pression publicitaire brute cumul\u00e9e de 1\u2019555.2&nbsp;millions de CHF<\/strong>, soit une hausse de 0.5% par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p class=\"wp-block-paragraph\">Au sein des cat\u00e9gories de m\u00e9dias classiques, le tableau est h\u00e9t\u00e9rog\u00e8ne: en mai, les secteurs <strong>M\u00e9dias imprim\u00e9s<\/strong> (-12.1%) et <strong>Radio<\/strong> (-14.1%) ont perdu des points de pourcentage par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente. En revanche, les secteurs <strong>T\u00e9l\u00e9vision<\/strong> (+4.3%), <strong>Out of Home<\/strong> (+10.5%) et surtout <strong>Cin\u00e9ma<\/strong> (+31.1%) affichent une nette hausse.  <\/p>\n<p class=\"wp-block-paragraph\">Sur le march\u00e9 num\u00e9rique, la pression publicitaire brute s\u2019est \u00e9lev\u00e9e en mai \u00e0 221.4\u00a0millions de CHF, soit un peu moins que le mois d\u2019avril (223.0\u00a0millions de CHF). La comparaison avec l\u2019ann\u00e9e pr\u00e9c\u00e9dente\u00a0\u2013 surtout en ce qui concerne Search et YouTube\u00a0\u2013 reste limit\u00e9e. <strong>Le canal Search<\/strong> domine avec une part de 68.9%, suivi par <strong>Display<\/strong> avec 24.0% et <strong>YouTube<\/strong> avec 7.1%<\/p>\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\" style=\"margin-top:0;margin-bottom:0\" \/>\n<h3 class=\"wp-block-heading\" style=\"font-size:25px\"><strong>Pression publicitaire sur le march\u00e9 global<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">\u00c9volution de la pression publicitaire au mois de mai&nbsp;2026 en millions de francs bruts.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Gesamtmarkt-klassisch-scaled.jpg\" alt=\"\" class=\"wp-image-196603\" style=\"width:1085px;height:auto\" \/><\/figure>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Monatsentwicklung-klassisch-scaled.jpg\" alt=\"\" class=\"wp-image-196606\" style=\"width:1085px;height:auto\" \/><\/figure>\n<h3 class=\"wp-block-heading\" style=\"font-size:18px\"><strong><strong>Toujours plus de secteurs \u00e0 l\u2019\u00e9volution positive<\/strong><\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Sur le march\u00e9 classique, <strong>12\u00a0secteurs sur\u00a021<\/strong> ont connu une \u00e9volution positive en mai. L\u2019image de tout le secteur est donc meilleure qu\u2019en avril. Le secteur <strong>Besoins Personnels <\/strong>affiche la plus forte augmentation en pourcentage avec une hausse de <strong>41.0%<\/strong>, suivi par le secteur <strong>Nettoyages<\/strong> (<strong>+37.3<\/strong>) et <strong>T\u00e9l\u00e9communication<\/strong> (<strong>+36.8%<\/strong>). Le secteur <strong>M\u00e9dias<\/strong> (<strong>+14.9%<\/strong>), <strong>V\u00e9hicules<\/strong> (<strong>+10.9%<\/strong>) et <strong>\u00c9nergie<\/strong> (<strong>+10.4%<\/strong>) connaissent \u00e9galement une \u00e9volution tr\u00e8s positive. Le secteur <strong>Cosm\u00e9tiques &amp; Soins Du Corps<\/strong> quant \u00e0 lui conna\u00eet une stagnation.<\/p>\n<h3 class=\"wp-block-heading\" style=\"font-size:18px\"><strong>Seuls neuf secteurs sont en recul<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">\u00c0 l\u2019inverse, neuf secteurs connaissent une baisse de leur pression publicitaire par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Les baisses en pourcentage les plus significatives ont \u00e9t\u00e9 observ\u00e9es dans le secteur <strong>Produits Tabagiques<\/strong> avec une baisse de <strong>37.5%<\/strong>, suivi par le secteur <strong>Prestation De Services<\/strong> (<strong>-21.7%<\/strong>) et <strong>Manifestations<\/strong> (<strong>-19.5%<\/strong>). Si le secteur <strong>Produits Alimentaires<\/strong> est \u00e9galement en recul avec une baisse de 3.7%, il reste toutefois le secteur \u00e0 la pression publicitaire la plus forte sur le march\u00e9 classique au mois de mai et en comparaison AAJ.<\/p>\n<p class=\"wp-block-paragraph\">Les secteurs <strong>Digital &amp; M\u00e9nage<\/strong> (<strong>-17.8%<\/strong>), <strong>Mode &amp; Sport<\/strong> (<strong>-15.6%<\/strong>), <strong>Loisir, Gastronomie, Tourisme<\/strong> (<strong>-9.4%<\/strong>) et <strong>Constructions, Industrie, Ameublement<\/strong> (<strong>-5.1%<\/strong>) sont \u00e9galement en recul. Le secteur<strong> Transports En Commun (-0.2%) <\/strong>est tout juste en n\u00e9gatif.<\/p>\n<h3 class=\"wp-block-heading\" style=\"font-size:20px\"><strong>Classement sectoriel<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Classement sectoriel de mai&nbsp;2026.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Branchenranking-klassisch-scaled.jpg\" alt=\"\" class=\"wp-image-196609\" style=\"width:1084px;height:auto\" \/><\/figure>\n<h3 class=\"wp-block-heading\" style=\"font-size:20px\"><strong>Les meilleurs annonceurs et produits<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Les meilleurs annonceurs et les produits et services les plus promus (hors promotion d\u2019assortiment et d\u2019image et hors cat\u00e9gories) en mai&nbsp;2026.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"987\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Top-Advertiser-klassisch-scaled.jpg\" alt=\"\" class=\"wp-image-196612\" \/><\/figure>\n<h3 class=\"wp-block-heading\" style=\"font-size:20px\"><strong>Mix de m\u00e9dias<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Mix de m\u00e9dias pour le mois de mai.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Media-Mix-klassisch-scaled.jpg\" alt=\"\" class=\"wp-image-196615\" style=\"width:1084px;height:auto\" \/><\/figure>\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-default\" \/>\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<h3 class=\"wp-block-heading\" style=\"font-size:25px\"><strong>Pression publicitaire sur le march\u00e9 num\u00e9rique<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">\u00c9volution de la pression publicitaire au mois de mai 2026 en millions de francs bruts.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Gesamtmarkt-digital-scaled.jpg\" alt=\"\" class=\"wp-image-196618\" style=\"width:1083px;height:auto\" \/><\/figure>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Monatsentwicklung-digital-scaled.jpg\" alt=\"\" class=\"wp-image-196621\" style=\"width:1083px;height:auto\" \/><\/figure>\n<p class=\"wp-block-paragraph\">*Pour une meilleure comparabilit\u00e9 avec l\u2019ann\u00e9e pr\u00e9c\u00e9dente, le march\u00e9 publicitaire classique et les canaux num\u00e9riques (Search, YouTube, Display) sont pr\u00e9sent\u00e9s s\u00e9par\u00e9ment. Les fluctuations de la saisie en ligne peuvent \u00eatre accentu\u00e9es par des influences externes, notamment des mises \u00e0 jour techniques de la part de grandes plateformes telles que Google ou YouTube. Cela concerne en particulier le domaine Search, qui subit r\u00e9guli\u00e8rement des changements susceptibles de nuire \u00e0 la comparabilit\u00e9 de la pression publicitaire brute avec l\u2019ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<h3 class=\"wp-block-heading\" style=\"font-size:18px\"><strong><strong><br \/>Classement sectoriel YTD: comparaison entre les canaux classiques et les canaux num\u00e9riques<\/strong><\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Bien qu\u2019il affiche un bilan n\u00e9gatif par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente, en mai, le secteur <strong>Produits Alimentaires<\/strong> \u00e9tait en t\u00eate du march\u00e9 classique. Le <strong>Commerce De D\u00e9tail<\/strong> et la <strong>Finance<\/strong> occupent les deuxi\u00e8me et troisi\u00e8me places, tous deux ayant g\u00e9n\u00e9r\u00e9 une pression publicitaire plus \u00e9lev\u00e9e en pourcentage par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Le secteur <strong>Finance<\/strong> se classe \u00e9galement dans le top&nbsp;3 du march\u00e9 num\u00e9rique en occupant la deuxi\u00e8me position entre <strong>Prestation De Services<\/strong> (3<sup>e<\/sup>&nbsp;place) et <strong>Loisir, Gastronomie, Tourisme <\/strong>(1<sup>re<\/sup>&nbsp;place).<\/p>\n<p class=\"wp-block-paragraph\">Il est particuli\u00e8rement frappant de constater que tous les secteurs, \u00e0 l\u2019exception de quatre d\u2019entre eux (Boissons, Cosm\u00e9tique &amp; Soins Du Corps, Manifestations et Nettoyages), ont progress\u00e9 par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente, alors que la situation est beaucoup plus h\u00e9t\u00e9rog\u00e8ne sur le march\u00e9 classique.<\/p>\n<p class=\"wp-block-paragraph\">La pond\u00e9ration diff\u00e9rente des divers secteurs m\u00e9rite \u00e9galement d\u2019\u00eatre soulign\u00e9e: le secteur <strong>Produits Alimentaires<\/strong> occupe la premi\u00e8re place sur le march\u00e9 classique, mais la douzi\u00e8me sur le march\u00e9 num\u00e9rique. \u00c0 l\u2019inverse, le secteur <strong>Prestation De Services<\/strong> occupe la douzi\u00e8me place sur le march\u00e9 classique, tandis qu\u2019il occupe la troisi\u00e8me place sur le march\u00e9 num\u00e9rique.<\/p>\n<p class=\"wp-block-paragraph\">Pour les deux classements, le secteur <strong>V\u00e9hicules <\/strong>se situe dans le tiers sup\u00e9rieur, le secteur <strong>Pharmaceutique &amp; Sant\u00e9<\/strong> ainsi que <strong>Mode &amp; Sport<\/strong> dans le tiers du milieu et <strong>M\u00e9dias<\/strong>, <strong>\u00c9nergie<\/strong>, <strong>Nettoyages<\/strong> et <strong>Produits Tabagiques<\/strong> dans le tiers inf\u00e9rieur.<\/p>\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<h3 class=\"wp-block-heading\" style=\"font-size:20px\"><strong>Classement sectoriel<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Classement sectoriel de mai 2026.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-SoA-digital-scaled.jpg\" alt=\"\" class=\"wp-image-196624\" style=\"width:1085px;height:auto\" \/><\/figure>\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<h3 class=\"wp-block-heading\" style=\"font-size:20px\"><strong>Les meilleurs produits num\u00e9riques<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Les produits et services les plus promus (hors promotion d\u2019assortiment et d\u2019image et hors cat\u00e9gories) en mai 2026.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"887\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Top-Produkte-digital-scaled.jpg\" alt=\"\" class=\"wp-image-196627\" style=\"width:1082px;height:auto\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Avec <strong>68.9%<\/strong>, le canal <strong>Search<\/strong> domine nettement le mix de m\u00e9dias et reste fortement influenc\u00e9 par les offres de voyage, ainsi que les offres comparatives et financi\u00e8res. Booking.com reste en t\u00eate, suivi de Comparis.ch et Skyscanner.ch. Ce classement \u00e9tait d\u00e9j\u00e0 le m\u00eame au mois d\u2019avril.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Display<\/strong> et <strong>YouTube<\/strong> pr\u00e9sentent un m\u00e9lange plus large entre t\u00e9l\u00e9communication, mobilit\u00e9, biens de consommation, divertissement et tourisme. La campagne Coop pour <strong>des-paroles-aux-actes.ch<\/strong> arrive en t\u00eate du classement pour <strong>Display<\/strong>. Viennent ensuite <strong>Denner Sponsoring<\/strong> en deuxi\u00e8me position et<strong> Pet-Recycling&nbsp;Schweiz<\/strong> en troisi\u00e8me position, ce qui fait gagner six places \u00e0 <strong>Denner Sponsoring<\/strong> par rapport au mois pr\u00e9c\u00e9dent. Sur <strong>YouTube<\/strong>, le jeu <strong>Yoshi and the mysterious book<\/strong> arrive en premi\u00e8re position, suivi de <strong>Tomodachi Life<\/strong>, qui occupait encore la troisi\u00e8me place le mois pr\u00e9c\u00e9dent, et de <strong>Pepsi Zero<\/strong>, le produit qui occupait la neuvi\u00e8me place le mois pr\u00e9c\u00e9dent. <strong>Pokemon Pokopia<\/strong> ferme la marche, alors qu\u2019il \u00e9tait en t\u00eate le mois dernier.<\/p>\n<p class=\"wp-block-paragraph\">La forte pr\u00e9sence de produits \u00e0 la nicotine alternatifs sur diff\u00e9rents canaux est \u00e9galement frappante: tandis que le syst\u00e8me de chauffage du tabac <strong>IQOS Tabak Heizsystem<\/strong> figure \u00e0 la 8<sup>e<\/sup>&nbsp;place des annonceurs Display les plus populaires, ZYN occupe la 4<sup>e<\/sup>&nbsp;place sur YouTube avec ses sachets <strong>ZYN Tabakfree Nicotine Pouches<\/strong>. Cela souligne l\u2019intensit\u00e9 toujours aussi \u00e9lev\u00e9e de l\u2019activit\u00e9 publicitaire dans le segment des produits \u00e0 base de nicotine sans combustion.<\/p>\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<h3 class=\"wp-block-heading\" style=\"font-size:20px\"><strong>Mix de m\u00e9dias<\/strong><\/h3>\n<p class=\"wp-block-paragraph\">Mix de m\u00e9dias pour le mois de mai 2026.<\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"2560\" height=\"1460\" src=\"https:\/\/werbekompass.ch\/wp-content\/uploads\/2026\/06\/FR-Werbemarkt-Trend-Mai-2026-Media-Mix-digital-scaled.jpg\" alt=\"\" class=\"wp-image-196630\" \/><\/figure>\n<p class=\"wp-block-paragraph\">\n<p class=\"wp-block-paragraph\">Contact: mediafocus@mediafocus.ch, Tel.: +41 43 322 27 50<\/p>\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mediafocus.ch\/fr\/publication\/resume-annuel-2025-le-marche-publicitaire-suisse\/\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e9sum\u00e9 annuel 2025<\/a><\/div>\n<\/div>\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-classique-se-stabilise-en-avril\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tendance du march\u00e9 publicitaire&nbsp;avril 2026<\/a><\/div>\n<\/div>\n<p class=\"wp-block-paragraph\">\n","protected":false},"excerpt":{"rendered":"<p>16.06.2026Le march\u00e9 publicitaire se montre stable en mai Tendance du march\u00e9 publicitaire&nbsp; Mai 2026 Apr\u00e8s un mois d\u2019avril stable, le mois de mai est \u00e9galement rest\u00e9 positif. Il a g\u00e9n\u00e9r\u00e9 354.6&nbsp;millions de CHF, soit un peu plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente (+0.2%). En mai, le march\u00e9 classique a atteint une pression publicitaire brute cumul\u00e9e de 1\u2019555.2&nbsp;millions [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"wbk_post_entry_category":[125,154,163],"wbk_post_entry_tag":[],"class_list":["post-649529","wbk_post_entry","type-wbk_post_entry","status-publish","format-standard","hentry","wbk_post_entry_category-tendance-du-marche-publicitaire","wbk_post_entry_category-publications-fr","wbk_post_entry_category-werbemarkttrend-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le march\u00e9 publicitaire se montre stable en mai - Media Focus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le march\u00e9 publicitaire se montre stable en mai - Media Focus\" \/>\n<meta property=\"og:description\" content=\"16.06.2026Le march\u00e9 publicitaire se montre stable en mai Tendance du march\u00e9 publicitaire&nbsp; Mai 2026 Apr\u00e8s un mois d\u2019avril stable, le mois de mai est \u00e9galement rest\u00e9 positif. Il a g\u00e9n\u00e9r\u00e9 354.6&nbsp;millions de CHF, soit un peu plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente (+0.2%). En mai, le march\u00e9 classique a atteint une pression publicitaire brute cumul\u00e9e de 1\u2019555.2&nbsp;millions [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/\" \/>\n<meta property=\"og:site_name\" content=\"Media Focus\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mediafocus.ch\/wp-content\/uploads\/2024\/10\/QuickGuide-WizzAd_DE-3-1-2-1-2-2-2-1-1-1-1-1-2-1-2-4-1-2-1-1-2-2-2-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1388\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/\",\"url\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/\",\"name\":\"Le march\u00e9 publicitaire se montre stable en mai - Media Focus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/werbekompass.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Titelbild-Pfeil-neu-1024x576.png\",\"datePublished\":\"2026-06-16T09:10:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/werbekompass.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Titelbild-Pfeil-neu-1024x576.png\",\"contentUrl\":\"https:\\\/\\\/werbekompass.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Titelbild-Pfeil-neu-1024x576.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/publication\\\/le-marche-publicitaire-se-montre-stable-en-mai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le march\u00e9 publicitaire se montre stable en mai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/\",\"name\":\"Media Focus\",\"description\":\"Data driven insights\",\"publisher\":{\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/#organization\",\"name\":\"Media Focus\",\"url\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mediafocus.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/media-focus-logo-mit-claim.svg\",\"contentUrl\":\"https:\\\/\\\/mediafocus.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/media-focus-logo-mit-claim.svg\",\"caption\":\"Media Focus\"},\"image\":{\"@id\":\"https:\\\/\\\/mediafocus.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le march\u00e9 publicitaire se montre stable en mai - Media Focus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/","og_locale":"fr_FR","og_type":"article","og_title":"Le march\u00e9 publicitaire se montre stable en mai - Media Focus","og_description":"16.06.2026Le march\u00e9 publicitaire se montre stable en mai Tendance du march\u00e9 publicitaire&nbsp; Mai 2026 Apr\u00e8s un mois d\u2019avril stable, le mois de mai est \u00e9galement rest\u00e9 positif. Il a g\u00e9n\u00e9r\u00e9 354.6&nbsp;millions de CHF, soit un peu plus que l\u2019ann\u00e9e pr\u00e9c\u00e9dente (+0.2%). En mai, le march\u00e9 classique a atteint une pression publicitaire brute cumul\u00e9e de 1\u2019555.2&nbsp;millions [&hellip;]","og_url":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/","og_site_name":"Media Focus","og_image":[{"width":1388,"height":774,"url":"https:\/\/mediafocus.ch\/wp-content\/uploads\/2024\/10\/QuickGuide-WizzAd_DE-3-1-2-1-2-2-2-1-1-1-1-1-2-1-2-4-1-2-1-1-2-2-2-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/","url":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/","name":"Le march\u00e9 publicitaire se montre stable en mai - Media Focus","isPartOf":{"@id":"https:\/\/mediafocus.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/#primaryimage"},"image":{"@id":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/#primaryimage"},"thumbnailUrl":"https:\/\/werbekompass.ch\/wp-content\/uploads\/2025\/02\/Titelbild-Pfeil-neu-1024x576.png","datePublished":"2026-06-16T09:10:49+00:00","breadcrumb":{"@id":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/#primaryimage","url":"https:\/\/werbekompass.ch\/wp-content\/uploads\/2025\/02\/Titelbild-Pfeil-neu-1024x576.png","contentUrl":"https:\/\/werbekompass.ch\/wp-content\/uploads\/2025\/02\/Titelbild-Pfeil-neu-1024x576.png"},{"@type":"BreadcrumbList","@id":"https:\/\/mediafocus.ch\/fr\/publication\/le-marche-publicitaire-se-montre-stable-en-mai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mediafocus.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Le march\u00e9 publicitaire se montre stable en mai"}]},{"@type":"WebSite","@id":"https:\/\/mediafocus.ch\/fr\/#website","url":"https:\/\/mediafocus.ch\/fr\/","name":"Media Focus","description":"Data driven insights","publisher":{"@id":"https:\/\/mediafocus.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mediafocus.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mediafocus.ch\/fr\/#organization","name":"Media Focus","url":"https:\/\/mediafocus.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mediafocus.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mediafocus.ch\/wp-content\/uploads\/2022\/05\/media-focus-logo-mit-claim.svg","contentUrl":"https:\/\/mediafocus.ch\/wp-content\/uploads\/2022\/05\/media-focus-logo-mit-claim.svg","caption":"Media Focus"},"image":{"@id":"https:\/\/mediafocus.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/wbk_post_entry\/649529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/wbk_post_entry"}],"about":[{"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/types\/wbk_post_entry"}],"replies":[{"embeddable":true,"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/comments?post=649529"}],"version-history":[{"count":0,"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/wbk_post_entry\/649529\/revisions"}],"wp:attachment":[{"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/media?parent=649529"}],"wp:term":[{"taxonomy":"wbk_post_entry_category","embeddable":true,"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/wbk_post_entry_category?post=649529"},{"taxonomy":"wbk_post_entry_tag","embeddable":true,"href":"https:\/\/mediafocus.ch\/fr\/wp-json\/wp\/v2\/wbk_post_entry_tag?post=649529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}